{"id":18367,"date":"2026-04-22T11:13:27","date_gmt":"2026-04-22T11:13:27","guid":{"rendered":"https:\/\/recettesrapides.milaf.ma\/?p=18367"},"modified":"2026-04-22T11:13:27","modified_gmt":"2026-04-22T11:13:27","slug":"mon-mari-se-rendait-quotidiennement-chez-son-frere-depuis-6-mois-lorsque-ma-belle-soeur-ma-appelee-dimanche-dernier-jai-ete-choquee","status":"publish","type":"post","link":"https:\/\/recette--faciles.milaf.ma\/index.php\/2026\/04\/22\/mon-mari-se-rendait-quotidiennement-chez-son-frere-depuis-6-mois-lorsque-ma-belle-soeur-ma-appelee-dimanche-dernier-jai-ete-choquee\/","title":{"rendered":"Mon mari se rendait quotidiennement chez son fr\u00e8re depuis 6 mois \u2014 Lorsque ma belle-s\u0153ur m\u2019a appel\u00e9e dimanche dernier, j\u2019ai \u00e9t\u00e9 choqu\u00e9e"},"content":{"rendered":"<p class=\"ContentRenderer_paragraph__B2z36 ContentRenderer_paragraph-first___d_VF\">Jeanne croyait avoir un mariage heureux et stable, mais les visites inexpliqu\u00e9es de John chez son fr\u00e8re la mettaient mal \u00e0 l\u2019aise. Un dimanche, un appel t\u00e9l\u00e9phonique de sa belle-s\u0153ur a r\u00e9v\u00e9l\u00e9 un secret choquant qui a boulevers\u00e9 le monde de Jeanne, pr\u00e9parant le terrain pour une confrontation qu\u2019elle n\u2019avait jamais pr\u00e9vue.<\/p>\n<div>\n<div class=\"adv\"><\/div>\n<\/div>\n<div>\n<p class=\"ContentRenderer_paragraph__B2z36\">Alors, je suis un peu dans tous mes \u00e9tats depuis dimanche et j\u2019ai besoin de m\u2019exprimer.<\/p>\n<\/div>\n<div>\n<p class=\"ContentRenderer_paragraph__B2z36\">Mon mari, John, et moi sommes ensemble depuis huit ans et mari\u00e9s depuis cinq ans. Nous avons un magnifique petit gar\u00e7on, Lucas, qui vient d\u2019avoir un an.<\/p>\n<\/div>\n<div>\n<div class=\"Image_wrapper__1NP9g Image_wrapper-vertical__PwZAR\">\n<div class=\"Image_container__oHMMQ\">\n<div class=\"Image_ref__XcBnw\"><picture><source srcset=\"https:\/\/imgproxy.amomama.fr\/u_I0jWP9atlRQlv6Oj5GOsKJ0Zgq7vTerm08K4CRwD8\/rs:fill:375:0:1\/g:no\/aHR0cHM6Ly9jZG4uYW1vbWFtYS5jb20vNjliNjUyNDNlMDYxMzMzNWEyZjBiMTM0OWQyYjIyMTM4MTQ2OGE1ZmVkM2JhMDkxZDE2MjZhOWZmMTk2ZDg4My5qcGc_d2lkdGg9MTkyMCZoZWlnaHQ9Mjg4MA.jpg 375w,https:\/\/imgproxy.amomama.fr\/m7_VLWoeYdDHiLw4byvvjwDIjjHRqihRkwgA57rQsac\/rs:fill:576:0:1\/g:no\/aHR0cHM6Ly9jZG4uYW1vbWFtYS5jb20vNjliNjUyNDNlMDYxMzMzNWEyZjBiMTM0OWQyYjIyMTM4MTQ2OGE1ZmVkM2JhMDkxZDE2MjZhOWZmMTk2ZDg4My5qcGc_d2lkdGg9MTkyMCZoZWlnaHQ9Mjg4MA.jpg 576w,https:\/\/imgproxy.amomama.fr\/6BKcBOLB4cgHlVBMz-X5tU1k0velFNYynTIWoVJvOFk\/rs:fill:768:0:1\/g:no\/aHR0cHM6Ly9jZG4uYW1vbWFtYS5jb20vNjliNjUyNDNlMDYxMzMzNWEyZjBiMTM0OWQyYjIyMTM4MTQ2OGE1ZmVkM2JhMDkxZDE2MjZhOWZmMTk2ZDg4My5qcGc_d2lkdGg9MTkyMCZoZWlnaHQ9Mjg4MA.jpg 768w,https:\/\/imgproxy.amomama.fr\/qplM1zBLZdeeYz0BFz0XffmMsEDbhrJZprPd7QL4Ntw\/rs:fill:992:0:1\/g:no\/aHR0cHM6Ly9jZG4uYW1vbWFtYS5jb20vNjliNjUyNDNlMDYxMzMzNWEyZjBiMTM0OWQyYjIyMTM4MTQ2OGE1ZmVkM2JhMDkxZDE2MjZhOWZmMTk2ZDg4My5qcGc_d2lkdGg9MTkyMCZoZWlnaHQ9Mjg4MA.jpg 992w,https:\/\/imgproxy.amomama.fr\/XwpDcHfos3BkemRe3HAjlJ4Z4_2Bubg2uOoJPx5RB4E\/rs:fill:1200:0:1\/g:no\/aHR0cHM6Ly9jZG4uYW1vbWFtYS5jb20vNjliNjUyNDNlMDYxMzMzNWEyZjBiMTM0OWQyYjIyMTM4MTQ2OGE1ZmVkM2JhMDkxZDE2MjZhOWZmMTk2ZDg4My5qcGc_d2lkdGg9MTkyMCZoZWlnaHQ9Mjg4MA.jpg 1200w\" type=\"image\/jpeg\" sizes=\"(max-width: 835px) 100vw, (max-width: 1279px) 581px, 581px\" \/><img loading=\"lazy\" decoding=\"async\" class=\"Image_image__11E9V Image_post-image__qnTn0\" src=\"https:\/\/cdn.amomama.fr\/69b65243e0613335a2f0b1349d2b221381468a5fed3ba091d1626a9ff196d883.jpg\" alt=\"Un couple qui joue avec son b\u00e9b\u00e9 | Source : Pexels\" width=\"1920\" height=\"2880\" \/><\/picture><\/div>\n<\/div>\n<p class=\"Image_title__T6_we\" data-testid=\"image-source\">Un couple qui joue avec son b\u00e9b\u00e9 | Source : Pexels<\/p>\n<\/div>\n<\/div>\n<div>\n<p class=\"ContentRenderer_paragraph__B2z36\">La vie a toujours \u00e9t\u00e9 bien remplie, mais nous avons r\u00e9ussi \u00e0 garder les choses ensemble. John est directeur de la construction, et je suis monitrice de fitness. Nos vies sont entrelac\u00e9es par des routines et un respect mutuel. Du moins, c\u2019est ce que je pensais.<\/p>\n<\/div>\n<div>\n<p class=\"ContentRenderer_paragraph__B2z36\">John a toujours \u00e9t\u00e9 un p\u00e8re de famille, et j\u2019admirais cela chez lui. Il se mettait en quatre pour aider son fr\u00e8re Clarke sur tout. Clarke et sa femme, Laurel, ont deux enfants, et leur famille est tr\u00e8s proche de la n\u00f4tre.<\/p>\n<\/div>\n<div>\n<div class=\"adv\"><\/div>\n<\/div>\n<div>\n<div class=\"Image_wrapper__1NP9g\">\n<div class=\"Image_container__oHMMQ\">\n<div class=\"Image_ref__XcBnw\"><picture><source srcset=\"https:\/\/imgproxy.amomama.fr\/clVNmoJEh1MX8OrgnBa4lYGuYK8JsrZhedudlpghbRc\/rs:fill:375:0:1\/g:no\/aHR0cHM6Ly9jZG4uYW1vbWFtYS5jb20vMGE2Njc4ZjhlYWIyMWYxODBiZTgyMWYyMDE0NzY5NTg5N2FlM2Y3NDZlY2IyZjVmNjRkMjczMGY4MWEzZDVkYi5qcGc_d2lkdGg9MTkyMCZoZWlnaHQ9MTI4MA.jpg 375w,https:\/\/imgproxy.amomama.fr\/W-NZdKDgEtK9iHaysDSTpJPLjtnSdcNGdrukh_YTMpY\/rs:fill:576:0:1\/g:no\/aHR0cHM6Ly9jZG4uYW1vbWFtYS5jb20vMGE2Njc4ZjhlYWIyMWYxODBiZTgyMWYyMDE0NzY5NTg5N2FlM2Y3NDZlY2IyZjVmNjRkMjczMGY4MWEzZDVkYi5qcGc_d2lkdGg9MTkyMCZoZWlnaHQ9MTI4MA.jpg 576w,https:\/\/imgproxy.amomama.fr\/Uw0edvQfTEy81I-zyT3uz7eRWHZVH2UFHC8T94XxrZU\/rs:fill:768:0:1\/g:no\/aHR0cHM6Ly9jZG4uYW1vbWFtYS5jb20vMGE2Njc4ZjhlYWIyMWYxODBiZTgyMWYyMDE0NzY5NTg5N2FlM2Y3NDZlY2IyZjVmNjRkMjczMGY4MWEzZDVkYi5qcGc_d2lkdGg9MTkyMCZoZWlnaHQ9MTI4MA.jpg 768w,https:\/\/imgproxy.amomama.fr\/ZywzQkJja5pgelRTcSP--B9MMR8Kl2o29t9p4IN4Qg0\/rs:fill:992:0:1\/g:no\/aHR0cHM6Ly9jZG4uYW1vbWFtYS5jb20vMGE2Njc4ZjhlYWIyMWYxODBiZTgyMWYyMDE0NzY5NTg5N2FlM2Y3NDZlY2IyZjVmNjRkMjczMGY4MWEzZDVkYi5qcGc_d2lkdGg9MTkyMCZoZWlnaHQ9MTI4MA.jpg 992w,https:\/\/imgproxy.amomama.fr\/4LKILqP-9n_gZxizGMc05HaJoZC_fVE9hkQ61eDOfUw\/rs:fill:1200:0:1\/g:no\/aHR0cHM6Ly9jZG4uYW1vbWFtYS5jb20vMGE2Njc4ZjhlYWIyMWYxODBiZTgyMWYyMDE0NzY5NTg5N2FlM2Y3NDZlY2IyZjVmNjRkMjczMGY4MWEzZDVkYi5qcGc_d2lkdGg9MTkyMCZoZWlnaHQ9MTI4MA.jpg 1200w\" type=\"image\/jpeg\" sizes=\"(max-width: 835px) 100vw, (max-width: 1279px) 830px, 830px\" \/><img loading=\"lazy\" decoding=\"async\" class=\"Image_image__11E9V Image_post-image__qnTn0\" src=\"https:\/\/cdn.amomama.fr\/0a6678f8eab21f180be821f20147695897ae3f746ecb2f5f64d2730f81a3d5db.jpg\" alt=\"Un couple avec ses deux enfants | Source : Pexels\" width=\"1920\" height=\"1280\" \/><\/picture><\/div>\n<\/div>\n<p class=\"Image_title__T6_we\" data-testid=\"image-source\">Un couple avec ses deux enfants | Source : Pexels<\/p>\n<\/div>\n<\/div>\n<div>\n<p class=\"ContentRenderer_paragraph__B2z36\">Mais au cours des six derniers mois, les visites quotidiennes de John chez Clarke sont devenues une routine. Au d\u00e9but, je n\u2019y ai pas pr\u00eat\u00e9 attention. Il avait toujours une raison : aider aux r\u00e9parations, rattraper le temps perdu avec son fr\u00e8re ou simplement respecter une \u00ab\u00a0tradition familiale\u00a0\u00bb \u00e0 laquelle il tenait.<\/p>\n<\/div>\n<div>\n<p class=\"ContentRenderer_paragraph__B2z36\">John partait \u00e0 l\u2019heure du d\u00eener et ne revenait que tard. C\u2019est devenu un point sensible entre nous, mais il avait toujours une excuse valable.<\/p>\n<\/div>\n<div>\n<div class=\"Image_wrapper__1NP9g\">\n<div class=\"Image_container__oHMMQ\">\n<div class=\"Image_ref__XcBnw\"><picture><source srcset=\"https:\/\/imgproxy.amomama.fr\/ceSn1rFFyQPf0QzsEskeOuFefv0brCf2gY8QD_rQEv0\/rs:fill:375:0:1\/g:no\/aHR0cHM6Ly9jZG4uYW1vbWFtYS5jb20vN2NjMWEzODU4NzBjZjIwZGYyZjkzMTJlMjVhNmFkOTZmNzc2ZWUxZjk5ZTE3MDU4MWE3MTkyYWZkYWYwNWQ3ZC5qcGc_d2lkdGg9MTkyMCZoZWlnaHQ9MTI4MA.jpg 375w,https:\/\/imgproxy.amomama.fr\/HKA5OQw7z5CbDk_tQPlZhmV-w5M-3zsAdsTtsUWiFAc\/rs:fill:576:0:1\/g:no\/aHR0cHM6Ly9jZG4uYW1vbWFtYS5jb20vN2NjMWEzODU4NzBjZjIwZGYyZjkzMTJlMjVhNmFkOTZmNzc2ZWUxZjk5ZTE3MDU4MWE3MTkyYWZkYWYwNWQ3ZC5qcGc_d2lkdGg9MTkyMCZoZWlnaHQ9MTI4MA.jpg 576w,https:\/\/imgproxy.amomama.fr\/y9nDIaxUKWvjKNqCAkrertmfHRx5kVXiuaatQtaPgi0\/rs:fill:768:0:1\/g:no\/aHR0cHM6Ly9jZG4uYW1vbWFtYS5jb20vN2NjMWEzODU4NzBjZjIwZGYyZjkzMTJlMjVhNmFkOTZmNzc2ZWUxZjk5ZTE3MDU4MWE3MTkyYWZkYWYwNWQ3ZC5qcGc_d2lkdGg9MTkyMCZoZWlnaHQ9MTI4MA.jpg 768w,https:\/\/imgproxy.amomama.fr\/yAx3yvhTrG7ePnbr6noBDgibU1hF2DOxeKvMr1blSQI\/rs:fill:992:0:1\/g:no\/aHR0cHM6Ly9jZG4uYW1vbWFtYS5jb20vN2NjMWEzODU4NzBjZjIwZGYyZjkzMTJlMjVhNmFkOTZmNzc2ZWUxZjk5ZTE3MDU4MWE3MTkyYWZkYWYwNWQ3ZC5qcGc_d2lkdGg9MTkyMCZoZWlnaHQ9MTI4MA.jpg 992w,https:\/\/imgproxy.amomama.fr\/MVELCqUFI_GxdwjyqdSzC1F5rhCS8AsolCYHt80Zj1A\/rs:fill:1200:0:1\/g:no\/aHR0cHM6Ly9jZG4uYW1vbWFtYS5jb20vN2NjMWEzODU4NzBjZjIwZGYyZjkzMTJlMjVhNmFkOTZmNzc2ZWUxZjk5ZTE3MDU4MWE3MTkyYWZkYWYwNWQ3ZC5qcGc_d2lkdGg9MTkyMCZoZWlnaHQ9MTI4MA.jpg 1200w\" type=\"image\/jpeg\" sizes=\"(max-width: 835px) 100vw, (max-width: 1279px) 830px, 830px\" \/><img loading=\"lazy\" decoding=\"async\" class=\"Image_image__11E9V Image_post-image__qnTn0\" src=\"https:\/\/cdn.amomama.fr\/7cc1a385870cf20df2f9312e25a6ad96f776ee1f99e170581a7192afdaf05d7d.jpg\" alt=\"Un homme jouant de la guitare pendant un d\u00eener en famille | Source : Pexels\" width=\"1920\" height=\"1280\" \/><\/picture><\/div>\n<\/div>\n<p class=\"Image_title__T6_we\" data-testid=\"image-source\">Un homme jouant de la guitare pendant un d\u00eener en famille | Source : Pexels<!--nextpage--><\/p>\n<p>\u00ab Jeanne, Clarke a besoin d\u2019aide avec la plomberie \u00bb, disait-il, ou \u00ab C\u2019est juste une visite rapide, je te le promets \u00bb.<\/p>\n<p>Parfois, c\u2019\u00e9tait : \u00ab Tu sais comment sont Clarke et Laurel ; ils ont toujours besoin d\u2019un coup de main suppl\u00e9mentaire avec les enfants. \u00bb<\/p>\n<p>Je lui faisais confiance, alors je laissais couler. Jusqu\u2019\u00e0 dimanche dernier, o\u00f9 tout a chang\u00e9.<\/p>\n<p>J\u2019\u00e9tais dans la cuisine, en train de donner \u00e0 manger son petit d\u00e9jeuner \u00e0 Lucas, quand mon t\u00e9l\u00e9phone a sonn\u00e9. C\u2019\u00e9tait Laurel, ma belle-s\u0153ur. Je pouvais dire qu\u2019elle \u00e9tait boulevers\u00e9e rien qu\u2019\u00e0 la fa\u00e7on dont elle m\u2019a dit bonjour.<\/p>\n<p>Une femme assise sur une chaise tout en nourrissant son b\u00e9b\u00e9 | Source : Pexels<br \/>\nUne femme assise sur une chaise tout en nourrissant son b\u00e9b\u00e9 | Source : Pexels<\/p>\n<p>\u00ab Jeanne, on peut parler ? \u00bb La voix de Laurel \u00e9tait tendue.<\/p>\n<p>\u00ab Bien s\u00fbr, Laurel. Qu\u2019est-ce qui se passe ? \u00bb, ai-je demand\u00e9, en essayant de garder un ton l\u00e9ger.<\/p>\n<p>\u00ab C\u2019est \u00e0 propos de John. Il vient tous les jours depuis six mois \u00bb, a-t-elle commenc\u00e9.<\/p>\n<p>\u00ab Oui, je sais. Il a beaucoup aid\u00e9 Clarke \u00bb, ai-je r\u00e9pondu.<\/p>\n<p>Elle a laiss\u00e9 \u00e9chapper un rire amer. \u00ab Aider ? Jeanne, il vient juste pour manger notre nourriture. As-tu la moindre id\u00e9e de ce que \u00e7a nous co\u00fbte ? \u00bb<\/p>\n<p>Je suis rest\u00e9e bouche b\u00e9e. \u00ab Qu\u2019est-ce que tu veux dire par manger votre nourriture ? Il m\u2019a dit qu\u2019il aidait Clarke \u00e0 faire des r\u00e9parations et d\u2019autres choses. \u00bb<\/p>\n<p>Une femme choqu\u00e9e qui parle au t\u00e9l\u00e9phone | Source : Midjourney<br \/>\nUne femme choqu\u00e9e qui parle au t\u00e9l\u00e9phone | Source : Midjourney<\/p>\n<p>\u00ab Bien s\u00fbr, il aide ici et l\u00e0, mais la plupart du temps, il se pr\u00e9sente juste pour le d\u00eener. Et \u00e7a s\u2019est accumul\u00e9. Nous ne pouvons pas nous permettre de nourrir une bouche suppl\u00e9mentaire tous les jours. Il faut que tu commences \u00e0 nous payer les courses. \u00bb<\/p>\n<p>Je n\u2019arrivais pas \u00e0 croire ce que j\u2019entendais. \u00ab Laurel, tu es s\u00e9rieuse ? John n\u2019a jamais parl\u00e9 de d\u00eener chez toi tous les jours. \u00bb<\/p>\n<p>\u00ab Oh, je suis s\u00e9rieuse. J\u2019ai fait le compte et j\u2019ai le montant exact que tu nous dois pour le mois dernier. C\u2019est 150 dollars. \u00bb<\/p>\n<p>Un homme en train de savourer son d\u00eener | Source : Pexels<br \/>\nUn homme en train de savourer son d\u00eener | Source : Pexels<\/p>\n<p>\u00ab $150 ? \u00bb, ai-je r\u00e9p\u00e9t\u00e9, mon esprit s\u2019emballant. \u00ab Ce n\u2019est pas possible. Il faut que j\u2019en parle \u00e0 John. \u00bb<\/p>\n<p>\u00ab S\u2019il te pla\u00eet, fais-le. Et fais-lui savoir que nous ne pouvons pas continuer \u00e0 faire \u00e7a. Nous avons nous-m\u00eames des difficult\u00e9s \u00bb, dit Laurel, son ton s\u2019adoucissant l\u00e9g\u00e8rement.<\/p>\n<p>\u00ab Bien s\u00fbr, je comprends. Je suis vraiment d\u00e9sol\u00e9e, Laurel. Je n\u2019en avais aucune id\u00e9e. Je lui parlerai ce soir. \u00bb<\/p>\n<p>\u00ab Merci, Jeanne. Je ne voulais pas causer d\u2019ennuis, mais c\u2019est trop pour nous \u00bb, a-t-elle dit avant de raccrocher.<\/p>\n<p>J\u2019\u00e9tais choqu\u00e9e. Je veux dire, je cuisine aussi ! Je cuisine, mais je suis tr\u00e8s soucieuse de ma sant\u00e9, surtout depuis la naissance de Lucas.<\/p>\n<p>Une femme mangeant des c\u00e9r\u00e9ales | Source : Pexels<br \/>\nUne femme mangeant des c\u00e9r\u00e9ales | Source : Pexels<\/p>\n<p>Je m\u2019efforce de rester en forme et de veiller \u00e0 ce que nous mangions des repas sains et \u00e9quilibr\u00e9s. Mais John faisait souvent des commentaires comme \u00ab Le go\u00fbt des vrais aliments me manque \u00bb ou \u00ab Ta cuisine est g\u00e9niale, mais parfois j\u2019ai envie de quelque chose de copieux. \u00bb<\/p>\n<p>Apr\u00e8s l\u2019appel de Laurel, j\u2019ai ressenti une temp\u00eate d\u2019\u00e9motions. Cela me faisait mal de penser que John s\u2019\u00e9clipsait pour profiter de la cuisine de quelqu\u2019un d\u2019autre au lieu de me dire simplement ce qu\u2019il ressentait.<\/p>\n<p>Lorsque John est rentr\u00e9 \u00e0 la maison ce soir-l\u00e0, j\u2019\u00e9tais pr\u00eate pour une confrontation.<\/p>\n<p>\u00ab John, il faut qu\u2019on parle \u00bb, ai-je dit en essayant de garder une voix stable.<\/p>\n<p>Une femme debout, les bras crois\u00e9s | Source : Midjourney<br \/>\nUne femme debout, les bras crois\u00e9s | Source : Midjourney<\/p>\n<p>\u00ab Bien s\u00fbr, qu\u2019est-ce qu\u2019il y a ? \u00bb, a-t-il r\u00e9pondu, l\u2019air un peu nerveux.<\/p>\n<p>\u00ab Laurel m\u2019a appel\u00e9e. Elle m\u2019a parl\u00e9 de tes visites quotidiennes et du fait que tu as mang\u00e9 sa nourriture tous les jours. Pourquoi ne me l\u2019as-tu pas dit ? \u00bb<\/p>\n<p>John a baiss\u00e9 les yeux, \u00e9vitant mon regard. \u00ab Je ne voulais pas te faire de peine, Jeanne. Ta cuisine est excellente, mais parfois le go\u00fbt de la vraie nourriture me manque, tu sais ? Les repas copieux et r\u00e9confortants que nous avions l\u2019habitude de prendre. \u00bb<\/p>\n<p>Une table \u00e0 manger remplie de repas traditionnels et classiques | Source : Midjourney<br \/>\nUne table \u00e0 manger remplie de repas traditionnels et classiques | Source : Midjourney<\/p>\n<p>Ma frustration a explos\u00e9. \u00ab Alors, tu te faufiles chez Clarke tous les jours au lieu de me dire ce que tu ressens ? Sais-tu \u00e0 quel point c\u2019est embarrassant de l\u2019apprendre par Laurel ? Et maintenant, elle veut que nous payions ses courses ! \u00bb<\/p>\n<p>Le visage de John rougit de culpabilit\u00e9. \u00ab Je suis d\u00e9sol\u00e9, Jeanne. Je ne voulais pas que \u00e7a d\u00e9g\u00e9n\u00e8re \u00e0 ce point. C\u2019est juste que\u2026 Le bon vieux temps me manque, les plats r\u00e9confortants. \u00bb<\/p>\n<p>\u00ab J\u2019ai essay\u00e9 de nous garder en bonne sant\u00e9, surtout apr\u00e8s la naissance de Lucas. Je pensais que tu le comprenais \u00bb, dis-je, ma voix se brisant un peu.<\/p>\n<p>Gros plan sur une femme pr\u00e9parant un sandwich | Source : Pexels<br \/>\nGros plan sur une femme pr\u00e9parant un sandwich | Source : Pexels<\/p>\n<p>\u00ab Je le comprends, Jeanne. J\u2019appr\u00e9cie tout ce que tu fais pour nous. C\u2019est juste que je n\u2019ai pas g\u00e9r\u00e9 \u00e7a de la bonne fa\u00e7on. S\u2019il te pla\u00eet, pardonne-moi \u00bb, dit-il, les yeux s\u00e9rieux et suppliants.<\/p>\n<p>J\u2019ai pris une grande inspiration, essayant de me calmer. \u00ab Tr\u00e8s bien. Voil\u00e0 ce que nous allons faire. Nous allons contribuer \u00e0 la facture d\u2019\u00e9picerie de Laurel, et j\u2019essaierai de pr\u00e9parer certains de ces plats classiques qui te manquent. Mais tu dois me promettre d\u2019\u00eatre honn\u00eate \u00e0 partir de maintenant. \u00bb<\/p>\n<p>John a acquiesc\u00e9, le soulagement se r\u00e9pandait sur son visage. \u00ab Je te le promets. Je parlerai \u00e0 Clarke et \u00e0 Laurel. \u00bb<\/p>\n<p>Une femme en train de cuisiner dans la cuisine | Source : Pexels<br \/>\nUne femme en train de cuisiner dans la cuisine | Source : Pexels<\/p>\n<p>Le lendemain matin, je me suis r\u00e9veill\u00e9e le c\u0153ur lourd mais avec la d\u00e9termination d\u2019arranger les choses.<\/p>\n<p>J\u2019ai d\u00e9cid\u00e9 d\u2019appeler Laurel. J\u2019ai compos\u00e9 son num\u00e9ro, sentant un n\u0153ud dans mon estomac.<\/p>\n<p>\u00ab Salut Laurel, c\u2019est Jeanne \u00ab , ai-je dit quand elle a d\u00e9croch\u00e9.<\/p>\n<p>\u00ab Bonjour, Jeanne. Comment tu tiens le coup ? \u00ab , m\u2019a-t-elle demand\u00e9, la voix plus douce que la veille.<\/p>\n<p>\u00ab Je vais bien, vu que. Je voulais te parler de la situation. John et moi nous sommes mis d\u2019accord pour contribuer \u00e0 tes factures. Qu\u2019en penses-tu ? \u00bb<\/p>\n<p>Une femme qui parle au t\u00e9l\u00e9phone | Source : Midjourney<br \/>\nUne femme qui parle au t\u00e9l\u00e9phone | Source : Midjourney<\/p>\n<p>\u00ab \u00c7a me semble juste. J\u2019appr\u00e9cie, Jeanne. Vraiment \u00bb, r\u00e9pondit Laurel, le soulagement \u00e9tant \u00e9vident dans son ton. \u00ab Et je veux que tu saches que je ne voulais pas causer de probl\u00e8mes entre toi et John \u00bb.<\/p>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Jeanne croyait avoir un mariage heureux et stable, mais les visites inexpliqu\u00e9es de John chez son fr\u00e8re la mettaient mal&hellip;<\/p>\n","protected":false},"author":1,"featured_media":18368,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-18367","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/recette--faciles.milaf.ma\/index.php\/wp-json\/wp\/v2\/posts\/18367","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/recette--faciles.milaf.ma\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/recette--faciles.milaf.ma\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/recette--faciles.milaf.ma\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/recette--faciles.milaf.ma\/index.php\/wp-json\/wp\/v2\/comments?post=18367"}],"version-history":[{"count":1,"href":"https:\/\/recette--faciles.milaf.ma\/index.php\/wp-json\/wp\/v2\/posts\/18367\/revisions"}],"predecessor-version":[{"id":18369,"href":"https:\/\/recette--faciles.milaf.ma\/index.php\/wp-json\/wp\/v2\/posts\/18367\/revisions\/18369"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/recette--faciles.milaf.ma\/index.php\/wp-json\/wp\/v2\/media\/18368"}],"wp:attachment":[{"href":"https:\/\/recette--faciles.milaf.ma\/index.php\/wp-json\/wp\/v2\/media?parent=18367"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/recette--faciles.milaf.ma\/index.php\/wp-json\/wp\/v2\/categories?post=18367"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/recette--faciles.milaf.ma\/index.php\/wp-json\/wp\/v2\/tags?post=18367"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}