{"id":17727,"date":"2026-04-14T15:30:32","date_gmt":"2026-04-14T15:30:32","guid":{"rendered":"https:\/\/recettesrapides.milaf.ma\/?p=17727"},"modified":"2026-04-14T15:30:32","modified_gmt":"2026-04-14T15:30:32","slug":"les-medecins-inquiets-lui-confirment-quil-sagit-dun-cavoir-plus","status":"publish","type":"post","link":"https:\/\/recette--faciles.milaf.ma\/index.php\/2026\/04\/14\/les-medecins-inquiets-lui-confirment-quil-sagit-dun-cavoir-plus\/","title":{"rendered":"Les m\u00e9decins inquiets lui confirment qu\u2019il s\u2019agit d\u2019un ca\u2026voir plus"},"content":{"rendered":"<div class=\"template_desktop_monetisation_item\" data-id=\"779952\">\n<h2 class=\"desktop_monet_title\">Propagation du variant NB.1.8.1 en Asie\u00a0<span class=\"desktop_monet_pagination\">(1\/12)<\/span><\/h2>\n<div class=\"diapo_vertical_excerpt\">\n<p>Apparu en Chine, le variant NB.1.8.1 du Covid-19 s\u2019est rapidement propag\u00e9 \u00e0 travers l\u2019Asie, atteignant des r\u00e9gions comme Hong Kong o\u00f9 un rebond significatif de l\u2019\u00e9pid\u00e9mie a \u00e9t\u00e9 observ\u00e9. Ce sous-lignage du variant Omicron, connu pour sa forte contagiosit\u00e9, a \u00e9t\u00e9 class\u00e9 par l\u2019Organisation mondiale de la Sant\u00e9 (OMS) comme un \u2018variant sous surveillance\u2019 le 23 mai. Cette classification, cr\u00e9\u00e9e en 2020, est r\u00e9serv\u00e9e aux variants pr\u00e9sentant un risque accru pour la sant\u00e9 publique.<\/p>\n<div class=\"google-anno-skip google-anno-sc\" tabindex=\"0\" role=\"link\" aria-label=\"Masques protection Covid\" data-google-vignette=\"false\" data-google-interstitial=\"false\">Masques protection Covid<\/div>\n<div class=\"google-anno-skip google-anno-sc\" tabindex=\"0\" role=\"link\" aria-label=\"\u00c9quipement sant\u00e9 publique\" data-google-vignette=\"false\" data-google-interstitial=\"false\">\u00c9quipement sant\u00e9 publique<\/div>\n<\/div>\n<\/div>\n<div class=\"template_desktop_monetisation_item\" data-id=\"779953\">\n<h2 class=\"desktop_monet_title\">Mutations importantes du variant NB.1.8.1\u00a0<span class=\"desktop_monet_pagination\">(2\/12)<\/span><\/h2>\n<div class=\"diapo_vertical_excerpt\">Le professeur Yves Buisson, membre de l\u2019Acad\u00e9mie nationale de m\u00e9decine, a soulign\u00e9 que le NB.1.8.1 pr\u00e9sente \u2018trois mutations assez importantes\u2019 par rapport \u00e0 son pr\u00e9d\u00e9cesseur, ce qui pourrait le rendre majoritaire \u00e0 l\u2019avenir. De son c\u00f4t\u00e9, le virologue Bruno Lina a d\u00e9clar\u00e9 \u00e0 BFMTV que les sp\u00e9cificit\u00e9s de ce variant pourraient le rendre dominant. En Asie, notamment \u00e0 Ta\u00efwan, le Centre national des maladies a rapport\u00e9 une hausse de 66% des consultations li\u00e9es au Covid-19 en une semaine.<\/div>\n<\/div>\n<div id=\"after_template_desktop_monetisation_items_2\" class=\"after_template_desktop_monetisation_item\">\n<div data-hbdbrk-parent=\"true\" data-actirise=\"true\" data-actirise-template=\"loader\">\n<div id=\"id-b28d20df-21f3-5d6b-8f64-005f8482d790-1\" data-hbdbrk=\"b28d20df-21f3-5d6b-8f64-005f8482d790\" data-hbdbrk-name=\"intext\"><\/div>\n<\/div>\n<div data-hbdbrk-parent=\"true\" data-actirise=\"true\" data-actirise-template=\"loader\">\n<div id=\"id-b28d20df-21f3-5d6b-8f64-005f8482d790-4\" data-hbdbrk=\"b28d20df-21f3-5d6b-8f64-005f8482d790\" data-hbdbrk-name=\"intext\"><\/div>\n<\/div>\n<\/div>\n<div class=\"template_desktop_monetisation_item\" data-id=\"779954\">\n<h2 class=\"desktop_monet_title\">Apparition du variant NB.1.8.1 en Europe et aux \u00c9tats-Unis\u00a0<span class=\"desktop_monet_pagination\">(3\/12)<\/span><\/h2>\n<div class=\"diapo_vertical_excerpt\">En Europe, le variant NB.1.8.1 a fait son apparition en Allemagne, en Irlande et aux Pays-Bas, avec la France recensant ses premiers cas en mars. Selon le Centre europ\u00e9en de pr\u00e9vention et de contr\u00f4le des maladies (ECDC), le variant circule depuis le d\u00e9but du mois d\u2019avril, mais son impact \u00e9pid\u00e9miologique reste incertain. Aux \u00c9tats-Unis, des cas ont \u00e9t\u00e9 d\u00e9tect\u00e9s chez des voyageurs internationaux arrivant dans plusieurs \u00c9tats, y compris la Californie et New York.<\/div>\n<div class=\"image-diaporama\">\n<div data-hbdbrk-inimage=\"2\" data-hbdbrk-inimage-type=\"image\">\n<p><img loading=\"lazy\" decoding=\"async\" class=\"template_desktop_monetisation_img img-responsive lazy-load lazy-loaded\" src=\"https:\/\/www.viepratique.fr\/wp-content\/uploads\/sites\/4\/2025\/07\/apparition-du-variant-nb-1-8-1-en-europe-et-aux-etats-unis-615x410.jpg\" width=\"615\" height=\"410\" data-src=\"https:\/\/www.viepratique.fr\/wp-content\/uploads\/sites\/4\/2025\/07\/apparition-du-variant-nb-1-8-1-en-europe-et-aux-etats-unis-615x410.jpg\" data-hbdbrk-img=\"1\" data-was-processed=\"true\" \/><\/p>\n<\/div>\n<div class=\"copyright_text_desktop\"><\/div>\n<div>la suite sur page suivant<!--nextpage--><\/div>\n<\/div>\n<div>\n<div class=\"template_desktop_monetisation_item\" data-id=\"779955\">\n<h2 class=\"desktop_monet_title\">L\u2019OMS rassure sur l\u2019efficacit\u00e9 des vaccins\u00a0<span class=\"desktop_monet_pagination\">(4\/12)<\/span><\/h2>\n<div class=\"diapo_vertical_excerpt\">L\u2019OMS a tenu \u00e0 rassurer le public en affirmant que les vaccins Covid-19 actuels devraient rester efficaces contre ce variant pour pr\u00e9venir les formes symptomatiques et graves de la maladie. Cependant, elle appelle \u00e0 la vigilance, notamment en Asie o\u00f9 le variant est devenu dominant. Hong Kong a signal\u00e9 que les principaux indicateurs de surveillance du Covid-19 atteignaient leur plus haut niveau depuis un an, incitant les autorit\u00e9s \u00e0 renforcer les mesures d\u2019hygi\u00e8ne.<\/div>\n<div class=\"image-diaporama\">\n<p><img loading=\"lazy\" decoding=\"async\" class=\"template_desktop_monetisation_img img-responsive\" src=\"https:\/\/www.viepratique.fr\/wp-content\/uploads\/sites\/4\/2025\/07\/loms-rassure-sur-lefficacite-des-vaccins-1024x683.jpg\" width=\"1024\" height=\"683\" data-hbdbrk-img=\"1\" \/><\/p>\n<div class=\"copyright_text_desktop\">\u00a9 Shutterstock<\/div>\n<\/div>\n<\/div>\n<div id=\"after_template_desktop_monetisation_items_4\" class=\"after_template_desktop_monetisation_item\">\n<div data-hbdbrk-parent=\"true\" data-actirise=\"true\" data-actirise-template=\"loader\">\n<div id=\"id-b28d20df-21f3-5d6b-8f64-005f8482d790-7\" data-hbdbrk=\"b28d20df-21f3-5d6b-8f64-005f8482d790\" data-hbdbrk-name=\"intext\">\n<div class=\"loader-grow\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"template_desktop_monetisation_item\" data-id=\"779956\">\n<h2 class=\"desktop_monet_title\">Augmentation des taux de tests positifs \u00e0 Hong Kong\u00a0<span class=\"desktop_monet_pagination\">(5\/12)<\/span><\/h2>\n<div class=\"diapo_vertical_excerpt\">Le pourcentage d\u2019\u00e9chantillons respiratoires test\u00e9s positifs au SRAS-CoV-2 \u00e0 Hong Kong a doubl\u00e9 en un mois, passant de 6,21 % \u00e0 13,66 %. De plus, la charge virale dans les eaux us\u00e9es a presque doubl\u00e9, atteignant 710 000 copies\/litre. Malgr\u00e9 ces chiffres alarmants, rien n\u2019indique pour l\u2019instant que le NB.1.8.1 provoque des formes plus graves de la maladie.<\/div>\n<div class=\"image-diaporama\">\n<p><img loading=\"lazy\" decoding=\"async\" class=\"template_desktop_monetisation_img img-responsive\" src=\"https:\/\/www.viepratique.fr\/wp-content\/uploads\/sites\/4\/2025\/07\/augmentation-des-taux-de-tests-positifs-a-hong-kong-1024x683.jpg\" width=\"1024\" height=\"683\" data-hbdbrk-img=\"1\" \/><\/p>\n<div class=\"copyright_text_desktop\">\u00a9 Shutterstock<\/div>\n<\/div>\n<\/div>\n<div id=\"after_template_desktop_monetisation_items_5\" class=\"after_template_desktop_monetisation_item\">\n<div data-hbdbrk-parent=\"true\" data-actirise=\"true\" data-actirise-template=\"loader\">\n<div id=\"id-b28d20df-21f3-5d6b-8f64-005f8482d790-9\" data-hbdbrk=\"b28d20df-21f3-5d6b-8f64-005f8482d790\" data-hbdbrk-name=\"intext\">\n<div class=\"loader-grow\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"template_desktop_monetisation_item\" data-id=\"779957\">\n<h2 class=\"desktop_monet_title\">Identification du variant NB.1.8.1 en France et aux \u00c9tats-Unis\u00a0<span class=\"desktop_monet_pagination\">(6\/12)<\/span><\/h2>\n<div class=\"diapo_vertical_excerpt\">En France, le variant a \u00e9t\u00e9 identifi\u00e9 \u00e0 quatre reprises, selon le Centre national de r\u00e9f\u00e9rence de Lyon. Aux \u00c9tats-Unis, des voyageurs en provenance de pays europ\u00e9ens, dont la France, ont \u00e9t\u00e9 test\u00e9s positifs entre fin avril et mi-mai. Le Centre europ\u00e9en de pr\u00e9vention et de contr\u00f4le des maladies n\u2019a pas encore plac\u00e9 le variant sous surveillance, mais suit son \u00e9volution de pr\u00e8s.<\/div>\n<div class=\"image-diaporama\">\n<p><img loading=\"lazy\" decoding=\"async\" class=\"template_desktop_monetisation_img img-responsive\" src=\"https:\/\/www.viepratique.fr\/wp-content\/uploads\/sites\/4\/2025\/07\/identification-du-variant-nb-1-8-1-en-france-et-aux-etats-unis-1024x682.jpg\" width=\"1024\" height=\"682\" data-hbdbrk-img=\"1\" \/><\/p>\n<div class=\"copyright_text_desktop\">\u00a9 Shutterstock<\/div>\n<\/div>\n<\/div>\n<div id=\"after_template_desktop_monetisation_items_6\" class=\"after_template_desktop_monetisation_item\">\n<div data-hbdbrk-parent=\"true\" data-actirise=\"true\" data-actirise-template=\"loader\">\n<div id=\"id-b28d20df-21f3-5d6b-8f64-005f8482d790-10\" data-hbdbrk=\"b28d20df-21f3-5d6b-8f64-005f8482d790\" data-hbdbrk-name=\"intext\"><\/div>\n<\/div>\n<div data-hbdbrk-parent=\"true\" data-actirise=\"true\" data-actirise-template=\"loader\">\n<div id=\"id-b28d20df-21f3-5d6b-8f64-005f8482d790-11\" data-hbdbrk=\"b28d20df-21f3-5d6b-8f64-005f8482d790\" data-hbdbrk-name=\"intext\"><\/div>\n<\/div>\n<\/div>\n<div class=\"template_desktop_monetisation_item\" data-id=\"779958\">\n<h2 class=\"desktop_monet_title\">Risque faible pour la sant\u00e9 publique mais transmissibilit\u00e9 accrue\u00a0<span class=\"desktop_monet_pagination\">(7\/12)<\/span><\/h2>\n<div class=\"diapo_vertical_excerpt\">\n<p>Selon l\u2019OMS, le risque suppl\u00e9mentaire pour la sant\u00e9 publique pos\u00e9 par le NB.1.8.1 est jug\u00e9 faible \u00e0 l\u2019\u00e9chelle mondiale. N\u00e9anmoins, les mutations observ\u00e9es pourraient accro\u00eetre sa transmissibilit\u00e9, ce qui n\u00e9cessite des \u00e9tudes suppl\u00e9mentaires. Les scientifiques s\u2019inqui\u00e8tent que ces mutations puissent r\u00e9duire l\u2019efficacit\u00e9 des anticorps et favoriser l\u2019\u00e9vasion immunitaire.<\/p>\n<div class=\"google-anno-skip google-anno-sc\" tabindex=\"0\" role=\"link\" aria-label=\"Acheter des vitamines et des compl\u00e9ments alimentaires\" data-google-vignette=\"false\" data-google-interstitial=\"false\">Acheter des vitamines et des compl\u00e9ments alimentaires<\/div>\n<\/div>\n<div class=\"image-diaporama\"><img loading=\"lazy\" decoding=\"async\" class=\"template_desktop_monetisation_img img-responsive\" src=\"https:\/\/www.viepratique.fr\/wp-content\/uploads\/sites\/4\/2025\/07\/risque-faible-pour-la-sante-publique-mais-transmissibilite-accrue-1024x683.jpg\" width=\"1024\" height=\"683\" data-hbdbrk-img=\"1\" \/><\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Propagation du variant NB.1.8.1 en Asie\u00a0(1\/12) Apparu en Chine, le variant NB.1.8.1 du Covid-19 s\u2019est rapidement propag\u00e9 \u00e0 travers l\u2019Asie,&hellip;<\/p>\n","protected":false},"author":1,"featured_media":17728,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-17727","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/recette--faciles.milaf.ma\/index.php\/wp-json\/wp\/v2\/posts\/17727","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/recette--faciles.milaf.ma\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/recette--faciles.milaf.ma\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/recette--faciles.milaf.ma\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/recette--faciles.milaf.ma\/index.php\/wp-json\/wp\/v2\/comments?post=17727"}],"version-history":[{"count":1,"href":"https:\/\/recette--faciles.milaf.ma\/index.php\/wp-json\/wp\/v2\/posts\/17727\/revisions"}],"predecessor-version":[{"id":17729,"href":"https:\/\/recette--faciles.milaf.ma\/index.php\/wp-json\/wp\/v2\/posts\/17727\/revisions\/17729"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/recette--faciles.milaf.ma\/index.php\/wp-json\/wp\/v2\/media\/17728"}],"wp:attachment":[{"href":"https:\/\/recette--faciles.milaf.ma\/index.php\/wp-json\/wp\/v2\/media?parent=17727"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/recette--faciles.milaf.ma\/index.php\/wp-json\/wp\/v2\/categories?post=17727"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/recette--faciles.milaf.ma\/index.php\/wp-json\/wp\/v2\/tags?post=17727"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}