{"id":17715,"date":"2026-04-14T15:26:45","date_gmt":"2026-04-14T15:26:45","guid":{"rendered":"https:\/\/recettesrapides.milaf.ma\/?p=17715"},"modified":"2026-04-14T15:26:45","modified_gmt":"2026-04-14T15:26:45","slug":"vos-ongles-se-cassent-ou-se-dedoublent-ce-detail-revele-un-ca","status":"publish","type":"post","link":"https:\/\/recette--faciles.milaf.ma\/index.php\/2026\/04\/14\/vos-ongles-se-cassent-ou-se-dedoublent-ce-detail-revele-un-ca\/","title":{"rendered":"Vos ongles se cassent ou se d\u00e9doublent : ce d\u00e9tail r\u00e9v\u00e8le un ca&#8230;"},"content":{"rendered":"<div class=\"page-article-lead\">\n<div class=\"page-article-subtitle\">\n<p>Il n\u2019est pas rare d\u2019observer des taches blanches, des stries sur nos ongles. Pire encore, \u00e0 certaines p\u00e9riodes, ces derniers peuvent devenir cassants. Mais qu\u2019est-ce que cela veut dire de notre sant\u00e9 ? Est-ce pr\u00e9occupant ? On fait le point.<\/p>\n<\/div>\n<\/div>\n<div class=\"page-article-text\">\n<p>Entre les manucures \u00e0 r\u00e9p\u00e9tition, la vaisselle, le jardinage, les bains chauds ou encore les microtraumatismes, nos ongles sont mis \u00e0 rude \u00e9preuve. Comme toutes les parties du corps, ces derniers peuvent subir des alt\u00e9rations. R\u00e9sultat, ils peuvent changer d\u2019aspect, se casser, se d\u00e9doubler et des taches blanches peuvent s\u2019y former. Ces derniers sont d\u2019ailleurs souvent le miroir d\u2019autres petits probl\u00e8mes de sant\u00e9. Une experte manucure O.P.I nous d\u00e9voile tout ce qu\u2019ils peuvent r\u00e9v\u00e9ler de notre sant\u00e9.<\/p>\n<h2 id=\"cjq0u\" class=\"no-inject-ads\"><strong>Ongle blanc\u00a0: pourquoi j\u2019ai des taches blanches sur les ongles des mains et des pieds\u00a0?<\/strong><\/h2>\n<p>Vous remarquez des petites taches blanches sur vos ongles\u00a0? Pas de panique, ces petites marques sont de simples bulles d\u2019air.\u00a0<em>\u201cRien \u00e0 voir avec des carences en calcium\u00a0!<\/em>\u00a0d\u00e9clare Alexandra Falba, experte manucure OPI. On laisse de c\u00f4t\u00e9 les id\u00e9es re\u00e7ues.\u00a0<em>\u201cL\u2019ongle est constitu\u00e9 de plusieurs dizaines de\u00a0<\/em><em><strong>feuillets de k\u00e9ratine<\/strong><\/em><em>\u00a0qui sont compress\u00e9s les uns aux autres,<\/em>\u00a0explique-t-elle,\u00a0<em>quand vous prenez un\u00a0<\/em><em><strong>microchoc\u00a0<\/strong><\/em><em>sur l\u2019ongle, les feuillets se d\u00e9collent les uns des autres superficiellement.\u201d<\/em>\u00a0C\u2019est ce ph\u00e9nom\u00e8ne qui cr\u00e9e l\u2019apparition de la tache blanche. Ces petites taches ne sont bien entendu pas \u00e0 confondre avec une leuconychie \u00e0 savoir une d\u00e9coloration de votre ongle.<\/p>\n<p>Les microchocs peuvent \u00eatre caus\u00e9s par toutes sortes d\u2019<strong>activit\u00e9s du quotidien<\/strong>\u00a0: le m\u00e9nage, le rongeage des ongles, le fait de taper sur les touches d\u2019un clavier d\u2019ordinateur, de faire la vaisselle\u2026 M\u00eame si \u00e7a n\u2019est pas douloureux, nos ongles peuvent en souffrir. Aussi \u00e9tonnant que cela puisse para\u00eetre, ces taches blanches peuvent se d\u00e9velopper sur vos orteils suite \u00e0 un choc ou une maladie des ongles\u00a0: la mycose.<!--nextpage--><\/p>\n<p>Comment les retirer\u00a0? Il n\u2019y a pas de rem\u00e8de\u00a0: d\u00e8s que la tache est install\u00e9e, il faut attendre que\u00a0l\u2019ongle repousse\u00a0pour qu\u2019elle disparaisse. Mais vous pouvez agir en pr\u00e9vention en ralentissant et en faisant attention \u00e0 vos gestes. Vous pouvez aussi\u00a0<em>\u201cmettre des gants lors d\u2019une activit\u00e9 qui pourrait causer des microchocs, pour att\u00e9nuer l\u2019impact sur l\u2019ongle\u201d<\/em>. Pensez-y lorsque vous lavez votre vaisselle ou que vous vous occupez de votre jardin. Enfin, pour \u201c<em>rendre l\u2019ongle plus souple<\/em>\u201d, la professionnelle conseille d\u2019appliquer quotidiennement une\u00a0huile v\u00e9g\u00e9tale\u00a0ou un baume car un ongle flexible et nourrit encaisse mieux les chocs.<\/p>\n<h2 id=\"2lkhk\" class=\"no-inject-ads\">Stries horizontales sur les ongles\u00a0: qu\u2019est-ce que cela signifie\u00a0?<\/h2>\n<p>Les\u00a0<strong>stries<\/strong>\u00a0peuvent avoir plusieurs origines. La premi\u00e8re est g\u00e9n\u00e9tique. Si vous avez des traits\u00a0<strong>verticaux ou horizontaux<\/strong>\u00a0sur les ongles depuis votre adolescence et que vos parents ont la m\u00eame chose, il se peut que la cause soit h\u00e9r\u00e9ditaire.<\/p>\n<p>La seconde cause est tout simplement\u2026 la\u00a0<strong>vieillesse<\/strong>,\u00a0<em>\u201cles stries sur l\u2019ongle sont l\u2019\u00e9quivalent des\u00a0<\/em><em>rides sur le visage<\/em><em>\u201d<\/em>, indique Alexandra Falba.\u00a0<em>\u201cPlus on prend de l\u2019\u00e2ge et plus on a de chance de voir appara\u00eetre ces stries\u201d.<\/em><\/p>\n<p>Enfin, il y en a dont l\u2019apparition est\u00a0<em>\u201cuniquement li\u00e9e \u00e0 une\u00a0<\/em><em><strong>s\u00e9cheresse excessive<\/strong><\/em><em>\u00a0de l\u2019ongle\u201d<\/em>. Quand il est sec,\u00a0<em>\u201cles feuillets de k\u00e9ratine ont du mal \u00e0 trouver une coh\u00e9rence les uns avec les autres, du coup les stries apparaissent\u201d<\/em>, constate l\u2019experte.<\/p>\n<p>Quelle que soit leur cause, il existe des solutions pour att\u00e9nuer l\u2019aspect de ces marques. D\u2019abord, appliquez un\u00a0<em>\u201cbaume \u00e9mollient, un baume nourrissant ou une\u00a0<\/em><em>huile v\u00e9g\u00e9tale<\/em><em>\u00a0quotidiennement sur la surface de l\u2019ongle en massant pour lui rendre sa souplesse, sa flexibilit\u00e9 et ainsi r\u00e9duire l\u2019apparition et l\u2019apparence des stries\u201d<\/em>. Ce massage permet aussi de nourrir la matrice (le tour de l\u2019ongle).<\/p>\n<p>Pour lisser la surface de l\u2019ongle, la professionnelle propose une autre solution\u00a0: la base comblante.\u00a0<em>\u201cElle est transparente au s\u00e9chage et permet de compenser les creux entre les stries\u201d<\/em>. Vous pouvez en trouver \u00e0 partir d\u2019environ 8\u00a0euros en parapharmacie, il peut s\u2019appliquer \u00e0 la place d\u2019une\u00a0base de vernis\u00a0classique.<\/p>\n<p>L\u2019utilisation de tout ce qui peut les effacer ou les abraser comme les limes ou les blocs ponce, est fortement d\u00e9conseill\u00e9e, sous peine de fragiliser l\u2019ongle encore plus.\u00a0<em>\u201cSur le moment c\u2019est une solution radicale, mais \u00e7a rend l\u2019<\/em><em>ongle mou<\/em><em>\u00a0et cassant\u201d<\/em>, pr\u00e9vient Alexandra Falba.<!--nextpage--><\/p>\n<h2 id=\"fsbl6\" class=\"no-inject-ads\"><strong>Ongles cassants\u00a0: quel probl\u00e8me \u00e7a cache et quelle est la cause\u00a0?<\/strong><\/h2>\n<p>Le d\u00e9doublement est souvent caus\u00e9 par une\u00a0<em>\u201cs\u00e9cheresse combin\u00e9e \u00e0<\/em>\u00a0<em>de petits chocs r\u00e9p\u00e9t\u00e9s sur le bord libre, c\u2019est-\u00e0-dire sur le bout des ongles\u201d,\u00a0<\/em>ce qui emp\u00eache une bonne croissance de l\u2019ongle<em>.<\/em>\u00a0Cela peut aussi \u00eatre d\u00fb \u00e0 une mauvaise alimentation, peu riche en nutriments. Sans ces \u00e9l\u00e9ments essentiels, la matrice qui fabrique l\u2019ongle sera de mauvaise qualit\u00e9. Or, si votre alimentation est saine et \u00e9quilibr\u00e9e, elle produira la pousse d\u2019un ongle plus r\u00e9sistant.<\/p>\n<p>En ce qui concerne les\u00a0ongles cassants, Alexandra Falba est claire :\u00a0<em>\u201cUn ongle cassant est syst\u00e9matiquement un ongle sec\u201d<\/em>. Cela signifie que\u00a0<strong>vous ne le nourrissez pas assez souvent avec des soins.<\/strong><\/p>\n<p>La solution \u00e0 ces deux probl\u00e8mes\u00a0? Prendre des\u00a0compl\u00e9ments alimentaires sp\u00e9cialis\u00e9s\u00a0dans la fortification des ongles ou riche en om\u00e9ga 3. Il est \u00e9galement conseill\u00e9 de\u00a0<em>\u201cporter ses ongles plus courts pour limiter le nombre de chocs qu\u2019ils re\u00e7oivent tous les jours et d\u2019appliquer<\/em>\u00a0<em>un baume ou une huile v\u00e9g\u00e9tale nourrissante tous les soirs avant de dormir\u201d<\/em>, explique la professionnelle.<\/p>\n<h2 id=\"ak424\" class=\"no-inject-ads\"><strong>Couleur des ongles\u00a0: pourquoi j\u2019ai les ongles jaunes\u00a0? Est-ce li\u00e9 \u00e0 une maladie\u00a0?<\/strong><\/h2>\n<p>En ce qui concerne le jaunissement\u00a0:\u00a0<em>\u201ctout est une histoire de sources ext\u00e9rieures\u201d,<\/em>\u00a0constate l\u2019experte OPI. La consommation de tabac est un des facteurs de jaunissement des ongles. Ce ph\u00e9nom\u00e8ne peut aussi s\u2019expliquer par\u00a0<strong>l\u2019oubli fr\u00e9quent d\u2019appliquer une base avant d\u2019\u00e9taler son vernis aux pigments color\u00e9s.<\/strong><\/p>\n<p>Comment garder des ongles bien blancs\u00a0?\u00a0<em>\u201cNe pas oublier de mettre une base avant le vernis, c\u2019est indispensable\u201d<\/em>. Ensuite, s\u2019ils sont d\u00e9j\u00e0 tach\u00e9s, deux solutions s\u2019offrent \u00e0 vous. Vous pouvez frotter vos ongles dans un demi-citron\u00a0<em>\u201ctous les jours jusqu\u2019\u00e0 ce qu\u2019ils \u00e9claircissent\u201d<\/em>\u00a0ou 1 \u00e0 2 fois par semaine pour entretenir la blancheur. Autrement, r\u00e9alisez une p\u00e2te \u00e9paisse \u00e0 base d\u2019eau et de bicarbonate soude et frotter le bout de vos doigts avec une brosse douce.\u00a0<em>\u201cPour voir des r\u00e9sultats, il faut r\u00e9it\u00e9rer le geste pendant au moins 4 jours\u201d<\/em>.<\/p>\n<p>Pour les plus inqui\u00e8tes d\u2019entre vous, rien ne vous emp\u00eache de consulter un m\u00e9decin traitant pour obtenir davantage d\u2019informations, et pourquoi pas un traitement si le besoin se pr\u00e9sente.<\/p>\n<p><em>Merci \u00e0 Alexandra Falba, experte manucure O.P.I pour ses conseils.<\/em><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Il n\u2019est pas rare d\u2019observer des taches blanches, des stries sur nos ongles. Pire encore, \u00e0 certaines p\u00e9riodes, ces derniers&hellip;<\/p>\n","protected":false},"author":1,"featured_media":17716,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-17715","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/recette--faciles.milaf.ma\/index.php\/wp-json\/wp\/v2\/posts\/17715","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/recette--faciles.milaf.ma\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/recette--faciles.milaf.ma\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/recette--faciles.milaf.ma\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/recette--faciles.milaf.ma\/index.php\/wp-json\/wp\/v2\/comments?post=17715"}],"version-history":[{"count":1,"href":"https:\/\/recette--faciles.milaf.ma\/index.php\/wp-json\/wp\/v2\/posts\/17715\/revisions"}],"predecessor-version":[{"id":17717,"href":"https:\/\/recette--faciles.milaf.ma\/index.php\/wp-json\/wp\/v2\/posts\/17715\/revisions\/17717"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/recette--faciles.milaf.ma\/index.php\/wp-json\/wp\/v2\/media\/17716"}],"wp:attachment":[{"href":"https:\/\/recette--faciles.milaf.ma\/index.php\/wp-json\/wp\/v2\/media?parent=17715"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/recette--faciles.milaf.ma\/index.php\/wp-json\/wp\/v2\/categories?post=17715"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/recette--faciles.milaf.ma\/index.php\/wp-json\/wp\/v2\/tags?post=17715"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}